{"id":1973,"count":1,"description":"","link":"https:\/\/www.miridiatech.com\/news\/tag\/traditional-medicine\/","name":"Traditional Medicine","slug":"traditional-medicine","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Traditional Medicine Archives - Acupuncture Technology News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.miridiatech.com\/news\/tag\/traditional-medicine\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Traditional Medicine Archives - Acupuncture Technology News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.miridiatech.com\/news\/tag\/traditional-medicine\/\" \/>\n<meta property=\"og:site_name\" content=\"Acupuncture Technology News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AcuGraph\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.miridiatech.com\\\/news\\\/tag\\\/traditional-medicine\\\/\",\"url\":\"https:\\\/\\\/www.miridiatech.com\\\/news\\\/tag\\\/traditional-medicine\\\/\",\"name\":\"Traditional Medicine Archives - Acupuncture Technology News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.miridiatech.com\\\/news\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.miridiatech.com\\\/news\\\/tag\\\/traditional-medicine\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.miridiatech.com\\\/news\\\/tag\\\/traditional-medicine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.miridiatech.com\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Traditional Medicine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.miridiatech.com\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.miridiatech.com\\\/news\\\/\",\"name\":\"Acupuncture Technology News\",\"description\":\"Ancient acupuncture with modern tools.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.miridiatech.com\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.miridiatech.com\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.miridiatech.com\\\/news\\\/#organization\",\"name\":\"Miridia Technology Inc.\",\"url\":\"https:\\\/\\\/www.miridiatech.com\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.miridiatech.com\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/www.miridiatech.com\\\/news\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/2011-M-Logo-Rebuild_Large_Dark.png?fit=1000%2C427&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/www.miridiatech.com\\\/news\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/2011-M-Logo-Rebuild_Large_Dark.png?fit=1000%2C427&ssl=1\",\"width\":1000,\"height\":427,\"caption\":\"Miridia Technology Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.miridiatech.com\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/pages\\\/AcuGraph\\\/336708131507\",\"https:\\\/\\\/x.com\\\/AcuGraph\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/miridiatech\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Traditional Medicine Archives - Acupuncture Technology News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.miridiatech.com\/news\/tag\/traditional-medicine\/","og_locale":"en_US","og_type":"article","og_title":"Traditional Medicine Archives - Acupuncture Technology News","og_url":"https:\/\/www.miridiatech.com\/news\/tag\/traditional-medicine\/","og_site_name":"Acupuncture Technology News","twitter_card":"summary_large_image","twitter_site":"@AcuGraph","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.miridiatech.com\/news\/tag\/traditional-medicine\/","url":"https:\/\/www.miridiatech.com\/news\/tag\/traditional-medicine\/","name":"Traditional Medicine Archives - Acupuncture Technology News","isPartOf":{"@id":"https:\/\/www.miridiatech.com\/news\/#website"},"breadcrumb":{"@id":"https:\/\/www.miridiatech.com\/news\/tag\/traditional-medicine\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.miridiatech.com\/news\/tag\/traditional-medicine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.miridiatech.com\/news\/"},{"@type":"ListItem","position":2,"name":"Traditional Medicine"}]},{"@type":"WebSite","@id":"https:\/\/www.miridiatech.com\/news\/#website","url":"https:\/\/www.miridiatech.com\/news\/","name":"Acupuncture Technology News","description":"Ancient acupuncture with modern tools.","publisher":{"@id":"https:\/\/www.miridiatech.com\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.miridiatech.com\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.miridiatech.com\/news\/#organization","name":"Miridia Technology Inc.","url":"https:\/\/www.miridiatech.com\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.miridiatech.com\/news\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/www.miridiatech.com\/news\/wp-content\/uploads\/2016\/10\/2011-M-Logo-Rebuild_Large_Dark.png?fit=1000%2C427&ssl=1","contentUrl":"https:\/\/i1.wp.com\/www.miridiatech.com\/news\/wp-content\/uploads\/2016\/10\/2011-M-Logo-Rebuild_Large_Dark.png?fit=1000%2C427&ssl=1","width":1000,"height":427,"caption":"Miridia Technology Inc."},"image":{"@id":"https:\/\/www.miridiatech.com\/news\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/pages\/AcuGraph\/336708131507","https:\/\/x.com\/AcuGraph","https:\/\/www.youtube.com\/user\/miridiatech"]}]}},"_links":{"self":[{"href":"https:\/\/www.miridiatech.com\/news\/wp-json\/wp\/v2\/tags\/1973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.miridiatech.com\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.miridiatech.com\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.miridiatech.com\/news\/wp-json\/wp\/v2\/posts?tags=1973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}